{"id":13349,"date":"2023-09-04T22:22:51","date_gmt":"2023-09-04T22:22:51","guid":{"rendered":"https:\/\/www.pucp.edu.pe\/climadecambios\/?p=13349"},"modified":"2023-09-04T22:28:08","modified_gmt":"2023-09-04T22:28:08","slug":"celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp","status":"publish","type":"post","link":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/","title":{"rendered":"Celebramos el D\u00eda del \u00c1rbol arborizando nuestro campus y barrio PUCP"},"content":{"rendered":"<h3><span style=\"font-weight: 400;\">El 1 y 2 de septiembre, la DARS, en coordinaci\u00f3n con la DAF y Clima de Cambios, se sum\u00f3 al reto de plantar 1 mill\u00f3n de \u00e1rboles a nivel nacional en la \u201cSegunda Gran Cruzada Verde Nacional\u00bb, organizada por el Ministerio del Ambiente en conmemoraci\u00f3n por el D\u00eda del \u00c1rbol.<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">En el marco de Campus Sostenible y Barrio PUCP, se convoc\u00f3 a un equipo voluntario para la arborizaci\u00f3n con 160 \u00e1rboles en tres zonas: el viernes 1 en la zona del bosque h\u00famedo tropical en el extremo sur del campus, y el s\u00e1bado 2 en la av. Universitaria frente al campus y en el parque Juan Pablo II, con la colaboraci\u00f3n de Plaza San Miguel.<\/span><\/p>\n<div id=\"attachment_13351\" style=\"width: 748px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-13351\" class=\"wp-image-13351 size-full\" src=\"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-content\/uploads\/2023\/09\/CUERPO-DE-TEXTO-1.jpg\" alt=\"\" width=\"738\" height=\"394\" srcset=\"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-content\/uploads\/2023\/09\/CUERPO-DE-TEXTO-1.jpg 738w, https:\/\/www.pucp.edu.pe\/climadecambios\/wp-content\/uploads\/2023\/09\/CUERPO-DE-TEXTO-1-300x160.jpg 300w\" sizes=\"auto, (max-width: 738px) 100vw, 738px\" \/><p id=\"caption-attachment-13351\" class=\"wp-caption-text\">El d\u00eda 1 se intervino la zona del bosque h\u00famedo tropical en el extremo sur del campus PUCP.<\/p><\/div>\n<p><span style=\"font-weight: 400;\">En el d\u00eda 1, la arborizaci\u00f3n por un campus sostenible, contamos con la participaci\u00f3n de Mariela Canepa, directora de la Direcci\u00f3n General de Diversidad Biol\u00f3gica del Minam, la Municipalidad de San Miguel y organizaciones estudiantiles. En esta oportunidad, los participantes recibieron una charla sobre el jard\u00edn bot\u00e1nico PUCP y las consideraciones para una correcta plantaci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el d\u00eda 2, iniciamos las actividades con las palabras de\u00a0 Silvana Vargas, directora de DARS; Jorge Rom\u00e1n, gerente municipal de la Municipalidad de San Miguel; Paola Sandoval, representante de Plaza San Miguel; y un representante de las organizaciones estudiantiles. A este equipo de voluntarios tambi\u00e9n se le dio una charla sobre las consideraciones para una correcta plantaci\u00f3n y as\u00ed se dio inicio a la actividad.<\/span><\/p>\n<div id=\"attachment_13352\" style=\"width: 748px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-13352\" class=\"wp-image-13352 size-full\" src=\"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-content\/uploads\/2023\/09\/CUERPO-DE-TEXTO-2.jpg\" alt=\"\" width=\"738\" height=\"394\" srcset=\"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-content\/uploads\/2023\/09\/CUERPO-DE-TEXTO-2.jpg 738w, https:\/\/www.pucp.edu.pe\/climadecambios\/wp-content\/uploads\/2023\/09\/CUERPO-DE-TEXTO-2-300x160.jpg 300w\" sizes=\"auto, (max-width: 738px) 100vw, 738px\" \/><p id=\"caption-attachment-13352\" class=\"wp-caption-text\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 El d\u00eda 2 se intervino la av. Universitaria frente al campus y en el parque Juan Pablo II.<\/p><\/div>\n<p><span style=\"font-weight: 400;\">Agradecemos a todas las personas voluntarias que participaron. Gracias a su labor conjunta, estamos sembrando acciones que nos permiten no solo reducir los impactos del cambio clim\u00e1tico, sino tambi\u00e9n crear h\u00e1bitos sostenibles que construyen un mejor entorno para todas las personas.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 1 y 2 de septiembre, la DARS, en coordinaci\u00f3n con la DAF y Clima de Cambios, se sum\u00f3 al reto de plantar 1 mill\u00f3n de \u00e1rboles a nivel nacional en la \u201cSegunda Gran Cruzada Verde Nacional\u00bb, organizada por el Ministerio del Ambiente en conmemoraci\u00f3n por el D\u00eda del \u00c1rbol. En el marco de Campus [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[276,707,728,727,717,726],"class_list":["post-13349","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-arboles","tag-arborizacion","tag-barrio-pucp","tag-campus-pucp","tag-campus-sostenible","tag-dia-del-arbol"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Celebramos el D\u00eda del \u00c1rbol arborizando nuestro campus y barrio PUCP<\/title>\n<meta name=\"description\" content=\"El 1 y 2 de septiembre, la DARS, en coordinaci\u00f3n con la DAF y Clima de Cambios, se sum\u00f3 al reto de plantar 1 mill\u00f3n de \u00e1rboles a nivel nacional en la \u201cSegunda Gran Cruzada Verde Nacional&quot;, organizada por el Ministerio del Ambiente en conmemoraci\u00f3n por el D\u00eda del \u00c1rbol.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celebramos el D\u00eda del \u00c1rbol arborizando nuestro campus y barrio PUCP\" \/>\n<meta property=\"og:description\" content=\"El 1 y 2 de septiembre, la DARS, en coordinaci\u00f3n con la DAF y Clima de Cambios, se sum\u00f3 al reto de plantar 1 mill\u00f3n de \u00e1rboles a nivel nacional en la \u201cSegunda Gran Cruzada Verde Nacional&quot;, organizada por el Ministerio del Ambiente en conmemoraci\u00f3n por el D\u00eda del \u00c1rbol.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/\" \/>\n<meta property=\"og:site_name\" content=\"Clima de cambios\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-04T22:22:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-04T22:28:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-content\/uploads\/2023\/09\/CUERPO-DE-TEXTO-1.jpg\" \/>\n<meta name=\"author\" content=\"Clima de Cambios\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Clima de Cambios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/\"},\"author\":{\"name\":\"Clima de Cambios\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79\"},\"headline\":\"Celebramos el D\u00eda del \u00c1rbol arborizando nuestro campus y barrio PUCP\",\"datePublished\":\"2023-09-04T22:22:51+00:00\",\"dateModified\":\"2023-09-04T22:28:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/\"},\"wordCount\":355,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-content\/uploads\/2023\/09\/CUERPO-DE-TEXTO-1.jpg\",\"keywords\":[\"\u00e1rboles\",\"arborizaci\u00f3n\",\"barrio PUCP\",\"campus PUCP\",\"campus sostenible\",\"d\u00eda del \u00e1rbol\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/\",\"url\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/\",\"name\":\"Celebramos el D\u00eda del \u00c1rbol arborizando nuestro campus y barrio PUCP\",\"isPartOf\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-content\/uploads\/2023\/09\/CUERPO-DE-TEXTO-1.jpg\",\"datePublished\":\"2023-09-04T22:22:51+00:00\",\"dateModified\":\"2023-09-04T22:28:08+00:00\",\"author\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79\"},\"description\":\"El 1 y 2 de septiembre, la DARS, en coordinaci\u00f3n con la DAF y Clima de Cambios, se sum\u00f3 al reto de plantar 1 mill\u00f3n de \u00e1rboles a nivel nacional en la \u201cSegunda Gran Cruzada Verde Nacional\\\", organizada por el Ministerio del Ambiente en conmemoraci\u00f3n por el D\u00eda del \u00c1rbol.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/#primaryimage\",\"url\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-content\/uploads\/2023\/09\/CUERPO-DE-TEXTO-1.jpg\",\"contentUrl\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-content\/uploads\/2023\/09\/CUERPO-DE-TEXTO-1.jpg\",\"width\":738,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Celebramos el D\u00eda del \u00c1rbol arborizando nuestro campus y barrio PUCP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#website\",\"url\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/\",\"name\":\"Clima de cambios\",\"description\":\"Clima de Cambios es una iniciativa medioambiental de la Pontificia Universidad Cat\u00f3lica del Per\u00fa para concientizar y sensibilizar a la ciudadan\u00eda sobre los efectos del cambio clim\u00e1tico en el Per\u00fa y el mundo.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79\",\"name\":\"Clima de Cambios\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/32dcd1482c4b98120225300dc5872038b3777d04f55b5565a634386d6edc6169?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/32dcd1482c4b98120225300dc5872038b3777d04f55b5565a634386d6edc6169?s=96&d=mm&r=g\",\"caption\":\"Clima de Cambios\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Celebramos el D\u00eda del \u00c1rbol arborizando nuestro campus y barrio PUCP","description":"El 1 y 2 de septiembre, la DARS, en coordinaci\u00f3n con la DAF y Clima de Cambios, se sum\u00f3 al reto de plantar 1 mill\u00f3n de \u00e1rboles a nivel nacional en la \u201cSegunda Gran Cruzada Verde Nacional\", organizada por el Ministerio del Ambiente en conmemoraci\u00f3n por el D\u00eda del \u00c1rbol.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/","og_locale":"es_ES","og_type":"article","og_title":"Celebramos el D\u00eda del \u00c1rbol arborizando nuestro campus y barrio PUCP","og_description":"El 1 y 2 de septiembre, la DARS, en coordinaci\u00f3n con la DAF y Clima de Cambios, se sum\u00f3 al reto de plantar 1 mill\u00f3n de \u00e1rboles a nivel nacional en la \u201cSegunda Gran Cruzada Verde Nacional\", organizada por el Ministerio del Ambiente en conmemoraci\u00f3n por el D\u00eda del \u00c1rbol.","og_url":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/","og_site_name":"Clima de cambios","article_published_time":"2023-09-04T22:22:51+00:00","article_modified_time":"2023-09-04T22:28:08+00:00","og_image":[{"url":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-content\/uploads\/2023\/09\/CUERPO-DE-TEXTO-1.jpg","type":"","width":"","height":""}],"author":"Clima de Cambios","twitter_misc":{"Escrito por":"Clima de Cambios","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/#article","isPartOf":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/"},"author":{"name":"Clima de Cambios","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79"},"headline":"Celebramos el D\u00eda del \u00c1rbol arborizando nuestro campus y barrio PUCP","datePublished":"2023-09-04T22:22:51+00:00","dateModified":"2023-09-04T22:28:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/"},"wordCount":355,"commentCount":0,"image":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-content\/uploads\/2023\/09\/CUERPO-DE-TEXTO-1.jpg","keywords":["\u00e1rboles","arborizaci\u00f3n","barrio PUCP","campus PUCP","campus sostenible","d\u00eda del \u00e1rbol"],"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/","url":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/","name":"Celebramos el D\u00eda del \u00c1rbol arborizando nuestro campus y barrio PUCP","isPartOf":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/#primaryimage"},"image":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-content\/uploads\/2023\/09\/CUERPO-DE-TEXTO-1.jpg","datePublished":"2023-09-04T22:22:51+00:00","dateModified":"2023-09-04T22:28:08+00:00","author":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79"},"description":"El 1 y 2 de septiembre, la DARS, en coordinaci\u00f3n con la DAF y Clima de Cambios, se sum\u00f3 al reto de plantar 1 mill\u00f3n de \u00e1rboles a nivel nacional en la \u201cSegunda Gran Cruzada Verde Nacional\", organizada por el Ministerio del Ambiente en conmemoraci\u00f3n por el D\u00eda del \u00c1rbol.","breadcrumb":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/#primaryimage","url":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-content\/uploads\/2023\/09\/CUERPO-DE-TEXTO-1.jpg","contentUrl":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-content\/uploads\/2023\/09\/CUERPO-DE-TEXTO-1.jpg","width":738,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/celebramos-el-dia-del-arbol-arborizando-nuestro-campus-y-barrio-pucp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pucp.edu.pe\/climadecambios\/"},{"@type":"ListItem","position":2,"name":"Celebramos el D\u00eda del \u00c1rbol arborizando nuestro campus y barrio PUCP"}]},{"@type":"WebSite","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#website","url":"https:\/\/www.pucp.edu.pe\/climadecambios\/","name":"Clima de cambios","description":"Clima de Cambios es una iniciativa medioambiental de la Pontificia Universidad Cat\u00f3lica del Per\u00fa para concientizar y sensibilizar a la ciudadan\u00eda sobre los efectos del cambio clim\u00e1tico en el Per\u00fa y el mundo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pucp.edu.pe\/climadecambios\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79","name":"Clima de Cambios","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/32dcd1482c4b98120225300dc5872038b3777d04f55b5565a634386d6edc6169?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32dcd1482c4b98120225300dc5872038b3777d04f55b5565a634386d6edc6169?s=96&d=mm&r=g","caption":"Clima de Cambios"}}]}},"_links":{"self":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts\/13349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/comments?post=13349"}],"version-history":[{"count":0,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts\/13349\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/media?parent=13349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/categories?post=13349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/tags?post=13349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}