{"id":13249,"date":"2023-04-10T20:34:48","date_gmt":"2023-04-10T20:34:48","guid":{"rendered":"https:\/\/www.pucp.edu.pe\/climadecambios\/?p=13249"},"modified":"2023-04-10T20:35:37","modified_gmt":"2023-04-10T20:35:37","slug":"que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas","status":"publish","type":"post","link":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/","title":{"rendered":"\u00bfQu\u00e9 necesita Lima para ser una ciudad segura para los ciclistas?"},"content":{"rendered":"<h3><span style=\"font-weight: 400;\">El n\u00famero de personas que se transporta en bicicleta ha ido aumentando desde el inicio de la pandemia. Sin embargo, la ciudad de Lima no es un espacio seguro para estos ciclistas. En esta nota, reflexionemos sobre la situaci\u00f3n de la micromovilidad en la capital y el rol que tenemos los ciudadanos para impulsar mejoras.<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Seg\u00fan datos del Observatorio Nacional de Seguridad Vial, entre enero a julio de 2022 el 60.9% de las personas fallecidas en siniestros viales son peatones o personas que iban a bordo de una bicicleta o motocicleta. Por otro lado, seg\u00fan un informe de la Municipalidad Metropolitana de Lima, existen construidos aproximadamente 291 km de ciclov\u00edas; sin embargo, estas no se encuentran interconectadas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como explica Nohelia Pasapera, docente del Departamento de Comunicaciones y experta en movilidad sostenible, ante este panorama es necesario pacificar las calles. \u201cTenemos grandes cantidades de personas moviliz\u00e1ndose de un extremo a otro de la ciudad, en donde impera la cultura del m\u00e1s fuerte\u201d. En ese sentido, algunas de las estrategias para lograr esta pacificaci\u00f3n implican la mejora de la infraestructura de las calles, incluyendo la luminaria, implementar pol\u00edticas de reducci\u00f3n de velocidad y fomentar una cultura vial. \u201cTenemos una cultura del auto reforzada en la publicidad y de ver como modelo de \u00e9xito al auto\u201d, reflexiona Pasapera.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-13251\" src=\"https:\/\/s3-us-west-2.amazonaws.com\/cdn01.pucp.education\/climadecambios\/wp-content\/uploads\/2023\/04\/10203129\/cuerpo-de-texto738%C3%97394px.png\" alt=\"\" width=\"738\" height=\"394\" \/><\/p>\n<p style=\"text-align: center;\">Fuente: Andina<\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s de este problema, est\u00e1 la fragmentaci\u00f3n de ciclov\u00edas y la falta de conexi\u00f3n entre tipos de transporte. \u201cExiste un problema de inequidad y tambi\u00e9n de exclusi\u00f3n, es decir, no hay intermodalidad. El sistema de transporte p\u00fablico no est\u00e1 conectado a la micromovilidad. Todo est\u00e1 fragmentado y las calles han sido dise\u00f1adas a imagen de los veh\u00edculos motorizados\u201d, indica la docente. Asimismo, se\u00f1ala que, durante la pandemia, aument\u00f3 en 2.4% el porcentaje de personas que se transportan en bicicleta; sin embargo, la ciudad no se ha adaptado a este tipo de movilidad.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si bien todas estas medidas y propuestas deber\u00edan ser implementadas idealmente por las autoridades municipales, la ciudadan\u00eda tambi\u00e9n tiene un rol activo que cumplir. A ra\u00edz del caso de Cecilia Doris Melgar Bravo, una exalumna de nuestra casa de estudios y ciclista que perdi\u00f3 la vida tras ser impactada por un volquete, surgieron movilizaciones, plantones y vigilias para exigir justicia y visibilizar la inseguridad que, a diario, enfrentan los ciclistas. \u201cEs importante no quedarnos en silencio, hacer comunidad y formar un colectivo que pueda reclamar sus derechos\u201d, recalca Pasapera.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De la misma forma, invit\u00f3 a que sean los usuarios de las calles quienes se involucren: \u201cQui\u00e9n mejor que el que usa los espacios p\u00fablicos para proponer. Esta conversaci\u00f3n entre los gobiernos, ya sean centrales, municipales, las autoridades y los usuarios, es bien importante porque finalmente son estos los que d\u00eda a d\u00eda est\u00e1n utilizando la infraestructura y los que pueden dar las mejores ideas\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En este mismo sentido, es fundamental que las personas no desistan del uso de la bicicleta. Como explica la experta, la \u00fanica manera de que la micromovilidad gane un espacio dentro de la ciudad es estando cada vez m\u00e1s presente. Esta visibilidad se debe generar de manera constante, y no hay mejor forma que impulsando y promoviendo el transporte en bicicleta. \u201cLas ciudades no son para los objetos, tienen que ser para las personas. Tenemos que empezar a ocupar las plazas, los espacios p\u00fablicos\u201d, comenta Pasapera. Algunos consejos de la docente para quienes tengan temor en usar la bicicleta son:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Iniciar recorriendo distancias cortas. Ir a la bodega o a la panader\u00eda y luego ampliar las distancias.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Realizar recorridos junto a colectivos de ciclistas. Los grupos que pasean por la ciudad son numerosos y las personas que participan tienen experiencia manejando bicicleta en la ciudad.<\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El n\u00famero de personas que se transporta en bicicleta ha ido aumentando desde el inicio de la pandemia. Sin embargo, la ciudad de Lima no es un espacio seguro para estos ciclistas. En esta nota, reflexionemos sobre la situaci\u00f3n de la micromovilidad en la capital y el rol que tenemos los ciudadanos para impulsar mejoras. [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[396,661,660,129,662,395],"class_list":["post-13249","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-bicicleta","tag-ciclistas","tag-ciudad-segura","tag-lima","tag-micromovilidad","tag-transporte-publico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 necesita Lima para ser una ciudad segura para los ciclistas?<\/title>\n<meta name=\"description\" content=\"El n\u00famero de personas que se transporta en bicicleta ha ido aumentando desde el inicio de la pandemia. Sin embargo, la ciudad de Lima no es un espacio seguro para estos ciclistas. En esta nota, reflexionemos sobre la situaci\u00f3n de la micromovilidad en la capital y el rol que tenemos los ciudadanos para impulsar mejoras.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 necesita Lima para ser una ciudad segura para los ciclistas?\" \/>\n<meta property=\"og:description\" content=\"El n\u00famero de personas que se transporta en bicicleta ha ido aumentando desde el inicio de la pandemia. Sin embargo, la ciudad de Lima no es un espacio seguro para estos ciclistas. En esta nota, reflexionemos sobre la situaci\u00f3n de la micromovilidad en la capital y el rol que tenemos los ciudadanos para impulsar mejoras.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/\" \/>\n<meta property=\"og:site_name\" content=\"Clima de cambios\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-10T20:34:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-10T20:35:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/s3-us-west-2.amazonaws.com\/cdn01.pucp.education\/climadecambios\/wp-content\/uploads\/2023\/04\/10203129\/cuerpo-de-texto738%C3%97394px.png\" \/>\n<meta name=\"author\" content=\"Clima de Cambios\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Clima de Cambios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/\"},\"author\":{\"name\":\"Clima de Cambios\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79\"},\"headline\":\"\u00bfQu\u00e9 necesita Lima para ser una ciudad segura para los ciclistas?\",\"datePublished\":\"2023-04-10T20:34:48+00:00\",\"dateModified\":\"2023-04-10T20:35:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/\"},\"wordCount\":648,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/s3-us-west-2.amazonaws.com\/cdn01.pucp.education\/climadecambios\/wp-content\/uploads\/2023\/04\/10203129\/cuerpo-de-texto738%C3%97394px.png\",\"keywords\":[\"bicicleta\",\"ciclistas\",\"ciudad segura\",\"lima\",\"micromovilidad\",\"transporte p\u00fablico\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/\",\"url\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/\",\"name\":\"\u00bfQu\u00e9 necesita Lima para ser una ciudad segura para los ciclistas?\",\"isPartOf\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/s3-us-west-2.amazonaws.com\/cdn01.pucp.education\/climadecambios\/wp-content\/uploads\/2023\/04\/10203129\/cuerpo-de-texto738%C3%97394px.png\",\"datePublished\":\"2023-04-10T20:34:48+00:00\",\"dateModified\":\"2023-04-10T20:35:37+00:00\",\"author\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79\"},\"description\":\"El n\u00famero de personas que se transporta en bicicleta ha ido aumentando desde el inicio de la pandemia. Sin embargo, la ciudad de Lima no es un espacio seguro para estos ciclistas. En esta nota, reflexionemos sobre la situaci\u00f3n de la micromovilidad en la capital y el rol que tenemos los ciudadanos para impulsar mejoras.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/#primaryimage\",\"url\":\"https:\/\/s3-us-west-2.amazonaws.com\/cdn01.pucp.education\/climadecambios\/wp-content\/uploads\/2023\/04\/10203129\/cuerpo-de-texto738%C3%97394px.png\",\"contentUrl\":\"https:\/\/s3-us-west-2.amazonaws.com\/cdn01.pucp.education\/climadecambios\/wp-content\/uploads\/2023\/04\/10203129\/cuerpo-de-texto738%C3%97394px.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 necesita Lima para ser una ciudad segura para los ciclistas?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#website\",\"url\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/\",\"name\":\"Clima de cambios\",\"description\":\"Clima de Cambios es una iniciativa medioambiental de la Pontificia Universidad Cat\u00f3lica del Per\u00fa para concientizar y sensibilizar a la ciudadan\u00eda sobre los efectos del cambio clim\u00e1tico en el Per\u00fa y el mundo.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79\",\"name\":\"Clima de Cambios\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/32dcd1482c4b98120225300dc5872038b3777d04f55b5565a634386d6edc6169?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/32dcd1482c4b98120225300dc5872038b3777d04f55b5565a634386d6edc6169?s=96&d=mm&r=g\",\"caption\":\"Clima de Cambios\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 necesita Lima para ser una ciudad segura para los ciclistas?","description":"El n\u00famero de personas que se transporta en bicicleta ha ido aumentando desde el inicio de la pandemia. Sin embargo, la ciudad de Lima no es un espacio seguro para estos ciclistas. En esta nota, reflexionemos sobre la situaci\u00f3n de la micromovilidad en la capital y el rol que tenemos los ciudadanos para impulsar mejoras.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 necesita Lima para ser una ciudad segura para los ciclistas?","og_description":"El n\u00famero de personas que se transporta en bicicleta ha ido aumentando desde el inicio de la pandemia. Sin embargo, la ciudad de Lima no es un espacio seguro para estos ciclistas. En esta nota, reflexionemos sobre la situaci\u00f3n de la micromovilidad en la capital y el rol que tenemos los ciudadanos para impulsar mejoras.","og_url":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/","og_site_name":"Clima de cambios","article_published_time":"2023-04-10T20:34:48+00:00","article_modified_time":"2023-04-10T20:35:37+00:00","og_image":[{"url":"https:\/\/s3-us-west-2.amazonaws.com\/cdn01.pucp.education\/climadecambios\/wp-content\/uploads\/2023\/04\/10203129\/cuerpo-de-texto738%C3%97394px.png","type":"","width":"","height":""}],"author":"Clima de Cambios","twitter_misc":{"Escrito por":"Clima de Cambios","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/#article","isPartOf":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/"},"author":{"name":"Clima de Cambios","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79"},"headline":"\u00bfQu\u00e9 necesita Lima para ser una ciudad segura para los ciclistas?","datePublished":"2023-04-10T20:34:48+00:00","dateModified":"2023-04-10T20:35:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/"},"wordCount":648,"commentCount":0,"image":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/#primaryimage"},"thumbnailUrl":"https:\/\/s3-us-west-2.amazonaws.com\/cdn01.pucp.education\/climadecambios\/wp-content\/uploads\/2023\/04\/10203129\/cuerpo-de-texto738%C3%97394px.png","keywords":["bicicleta","ciclistas","ciudad segura","lima","micromovilidad","transporte p\u00fablico"],"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/","url":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/","name":"\u00bfQu\u00e9 necesita Lima para ser una ciudad segura para los ciclistas?","isPartOf":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/#primaryimage"},"image":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/#primaryimage"},"thumbnailUrl":"https:\/\/s3-us-west-2.amazonaws.com\/cdn01.pucp.education\/climadecambios\/wp-content\/uploads\/2023\/04\/10203129\/cuerpo-de-texto738%C3%97394px.png","datePublished":"2023-04-10T20:34:48+00:00","dateModified":"2023-04-10T20:35:37+00:00","author":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79"},"description":"El n\u00famero de personas que se transporta en bicicleta ha ido aumentando desde el inicio de la pandemia. Sin embargo, la ciudad de Lima no es un espacio seguro para estos ciclistas. En esta nota, reflexionemos sobre la situaci\u00f3n de la micromovilidad en la capital y el rol que tenemos los ciudadanos para impulsar mejoras.","breadcrumb":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/#primaryimage","url":"https:\/\/s3-us-west-2.amazonaws.com\/cdn01.pucp.education\/climadecambios\/wp-content\/uploads\/2023\/04\/10203129\/cuerpo-de-texto738%C3%97394px.png","contentUrl":"https:\/\/s3-us-west-2.amazonaws.com\/cdn01.pucp.education\/climadecambios\/wp-content\/uploads\/2023\/04\/10203129\/cuerpo-de-texto738%C3%97394px.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/que-necesita-lima-para-ser-una-ciudad-segura-para-los-ciclistas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pucp.edu.pe\/climadecambios\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 necesita Lima para ser una ciudad segura para los ciclistas?"}]},{"@type":"WebSite","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#website","url":"https:\/\/www.pucp.edu.pe\/climadecambios\/","name":"Clima de cambios","description":"Clima de Cambios es una iniciativa medioambiental de la Pontificia Universidad Cat\u00f3lica del Per\u00fa para concientizar y sensibilizar a la ciudadan\u00eda sobre los efectos del cambio clim\u00e1tico en el Per\u00fa y el mundo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pucp.edu.pe\/climadecambios\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79","name":"Clima de Cambios","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/32dcd1482c4b98120225300dc5872038b3777d04f55b5565a634386d6edc6169?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32dcd1482c4b98120225300dc5872038b3777d04f55b5565a634386d6edc6169?s=96&d=mm&r=g","caption":"Clima de Cambios"}}]}},"_links":{"self":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts\/13249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/comments?post=13249"}],"version-history":[{"count":0,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts\/13249\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/media?parent=13249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/categories?post=13249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/tags?post=13249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}