{"id":13187,"date":"2022-06-10T23:44:38","date_gmt":"2022-06-10T23:44:38","guid":{"rendered":"https:\/\/www.pucp.edu.pe\/climadecambios\/?p=13187"},"modified":"2022-06-10T23:46:46","modified_gmt":"2022-06-10T23:46:46","slug":"revive-aqui-el-primer-conversatorio-dialogos-por-la-bici","status":"publish","type":"post","link":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/","title":{"rendered":"Revive aqu\u00ed el primer conversatorio \u201cDi\u00e1logos por la bici\u00bb"},"content":{"rendered":"<p><strong>El evento, suscitado en el marco del D\u00eda Mundial de la Bicicleta, surgi\u00f3 de la iniciativa Mu\u00e9vete en bici para promover el uso de la bicicleta al trasladarse hacia la Universidad, y ser as\u00ed una sociedad m\u00e1s sostenible, limpia y saludable.\u00a0<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">El evento \u201cDi\u00e1logos por la bici\u201d, organizado por la Direcci\u00f3n Acad\u00e9mica de Responsabilidad Social &#8211; DARS y Clima de Cambios, sirvi\u00f3 como un punto de encuentro para reflexionar sobre las experiencias de las tres principales agrupaciones universitarias que promueven el uso de la bicicleta, pero tambi\u00e9n fue un momento de diversi\u00f3n y sorpresas para quienes reci\u00e9n inician este estilo de vida, participando incluso en el sorteo en vivo de una bici.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mira aqu\u00ed el video:<\/span><\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/FwTnledOqzE\" width=\"560\" height=\"314\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><span style=\"font-weight: 400;\"><br \/>\nConsciente del papel determinante que juega la Universidad, la comunidad PUCP, a trav\u00e9s de la iniciativa Mu\u00e9vete en bici, continuar\u00e1 brindando\u00a0 algunos recursos \u00fatiles para los alumnos que llegan al campus sobre dos ruedas aportando con proyectos, como el mapa de rutas, entrevistas con expertos y m\u00e1s.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El evento, suscitado en el marco del D\u00eda Mundial de la Bicicleta, surgi\u00f3 de la iniciativa Mu\u00e9vete en bici para promover el uso de la bicicleta al trasladarse hacia la Universidad, y ser as\u00ed una sociedad m\u00e1s sostenible, limpia y saludable.\u00a0 El evento \u201cDi\u00e1logos por la bici\u201d, organizado por la Direcci\u00f3n Acad\u00e9mica de Responsabilidad Social [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[396,124,607,501,610,606],"class_list":["post-13187","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-bicicleta","tag-clima-de-cambios","tag-conversatorio","tag-dars","tag-dia-mundial-de-la-bicicleta","tag-dialogos-por-la-bici"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Revive aqu\u00ed el primer conversatorio \u201cDi\u00e1logos por la bici&quot; - Clima de cambios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Revive aqu\u00ed el primer conversatorio \u201cDi\u00e1logos por la bici&quot; - Clima de cambios\" \/>\n<meta property=\"og:description\" content=\"El evento, suscitado en el marco del D\u00eda Mundial de la Bicicleta, surgi\u00f3 de la iniciativa Mu\u00e9vete en bici para promover el uso de la bicicleta al trasladarse hacia la Universidad, y ser as\u00ed una sociedad m\u00e1s sostenible, limpia y saludable.\u00a0 El evento \u201cDi\u00e1logos por la bici\u201d, organizado por la Direcci\u00f3n Acad\u00e9mica de Responsabilidad Social [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/\" \/>\n<meta property=\"og:site_name\" content=\"Clima de cambios\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-10T23:44:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-10T23:46:46+00:00\" \/>\n<meta name=\"author\" content=\"Clima de Cambios\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Clima de Cambios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/\"},\"author\":{\"name\":\"Clima de Cambios\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79\"},\"headline\":\"Revive aqu\u00ed el primer conversatorio \u201cDi\u00e1logos por la bici\u00bb\",\"datePublished\":\"2022-06-10T23:44:38+00:00\",\"dateModified\":\"2022-06-10T23:46:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/\"},\"wordCount\":185,\"commentCount\":0,\"keywords\":[\"bicicleta\",\"clima de cambios\",\"conversatorio\",\"DARS\",\"d\u00eda mundial de la bicicleta\",\"di\u00e1logos por la bici\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/\",\"url\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/\",\"name\":\"Revive aqu\u00ed el primer conversatorio \u201cDi\u00e1logos por la bici\\\" - Clima de cambios\",\"isPartOf\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#website\"},\"datePublished\":\"2022-06-10T23:44:38+00:00\",\"dateModified\":\"2022-06-10T23:46:46+00:00\",\"author\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Revive aqu\u00ed el primer conversatorio \u201cDi\u00e1logos por la bici\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#website\",\"url\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/\",\"name\":\"Clima de cambios\",\"description\":\"Clima de Cambios es una iniciativa medioambiental de la Pontificia Universidad Cat\u00f3lica del Per\u00fa para concientizar y sensibilizar a la ciudadan\u00eda sobre los efectos del cambio clim\u00e1tico en el Per\u00fa y el mundo.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79\",\"name\":\"Clima de Cambios\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/32dcd1482c4b98120225300dc5872038b3777d04f55b5565a634386d6edc6169?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/32dcd1482c4b98120225300dc5872038b3777d04f55b5565a634386d6edc6169?s=96&d=mm&r=g\",\"caption\":\"Clima de Cambios\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Revive aqu\u00ed el primer conversatorio \u201cDi\u00e1logos por la bici\" - Clima de cambios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/","og_locale":"es_ES","og_type":"article","og_title":"Revive aqu\u00ed el primer conversatorio \u201cDi\u00e1logos por la bici\" - Clima de cambios","og_description":"El evento, suscitado en el marco del D\u00eda Mundial de la Bicicleta, surgi\u00f3 de la iniciativa Mu\u00e9vete en bici para promover el uso de la bicicleta al trasladarse hacia la Universidad, y ser as\u00ed una sociedad m\u00e1s sostenible, limpia y saludable.\u00a0 El evento \u201cDi\u00e1logos por la bici\u201d, organizado por la Direcci\u00f3n Acad\u00e9mica de Responsabilidad Social [&hellip;]","og_url":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/","og_site_name":"Clima de cambios","article_published_time":"2022-06-10T23:44:38+00:00","article_modified_time":"2022-06-10T23:46:46+00:00","author":"Clima de Cambios","twitter_misc":{"Escrito por":"Clima de Cambios","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/#article","isPartOf":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/"},"author":{"name":"Clima de Cambios","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79"},"headline":"Revive aqu\u00ed el primer conversatorio \u201cDi\u00e1logos por la bici\u00bb","datePublished":"2022-06-10T23:44:38+00:00","dateModified":"2022-06-10T23:46:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/"},"wordCount":185,"commentCount":0,"keywords":["bicicleta","clima de cambios","conversatorio","DARS","d\u00eda mundial de la bicicleta","di\u00e1logos por la bici"],"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/","url":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/","name":"Revive aqu\u00ed el primer conversatorio \u201cDi\u00e1logos por la bici\" - Clima de cambios","isPartOf":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#website"},"datePublished":"2022-06-10T23:44:38+00:00","dateModified":"2022-06-10T23:46:46+00:00","author":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79"},"breadcrumb":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/revive-aqui-el-primer-conversatorio-dialogos-por-la-bici\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pucp.edu.pe\/climadecambios\/"},{"@type":"ListItem","position":2,"name":"Revive aqu\u00ed el primer conversatorio \u201cDi\u00e1logos por la bici\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#website","url":"https:\/\/www.pucp.edu.pe\/climadecambios\/","name":"Clima de cambios","description":"Clima de Cambios es una iniciativa medioambiental de la Pontificia Universidad Cat\u00f3lica del Per\u00fa para concientizar y sensibilizar a la ciudadan\u00eda sobre los efectos del cambio clim\u00e1tico en el Per\u00fa y el mundo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pucp.edu.pe\/climadecambios\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79","name":"Clima de Cambios","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/32dcd1482c4b98120225300dc5872038b3777d04f55b5565a634386d6edc6169?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32dcd1482c4b98120225300dc5872038b3777d04f55b5565a634386d6edc6169?s=96&d=mm&r=g","caption":"Clima de Cambios"}}]}},"_links":{"self":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts\/13187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/comments?post=13187"}],"version-history":[{"count":0,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts\/13187\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/media?parent=13187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/categories?post=13187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/tags?post=13187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}