{"id":12401,"date":"2018-12-21T16:14:16","date_gmt":"2018-12-21T16:14:16","guid":{"rendered":"https:\/\/www.pucp.edu.pe\/climadecambios\/?p=12401"},"modified":"2018-12-21T16:25:13","modified_gmt":"2018-12-21T16:25:13","slug":"igua-este-verano-queremos-compartir-100-000-litros-de-agua","status":"publish","type":"post","link":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/","title":{"rendered":"IGUA: Este verano, queremos compartir 100 000 litros de agua"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"><strong>IGUA es una empresa social que tiene como finalidad brindar puntos de hidrataci\u00f3n en diversos lugares de la ciudad y garantizar el consumo de agua purificada y sostenible en el Per\u00fa.<\/strong> Clima de Cambios convers\u00f3 con Jos\u00e9 Corso, fundador de IGUA sobre la creaci\u00f3n de este proyecto.<\/span><\/p>\n<p><b>\u00bfCu\u00e1l fue la motivaci\u00f3n para crear IGUA?<br \/>\n<\/b><span style=\"font-weight: 400;\">Hacer algo bueno para todos y que eso pueda generar un mejor planeta<\/span><b>. Quer\u00eda promover que la gente tome agua y transformar la manera en como lo hac\u00edan, pero al mismo tiempo hacer cosas positivas por el medio ambiente.<\/b><\/p>\n<p><b>\u00bfC\u00f3mo funciona la dispensadora?<br \/>\n<\/b><b>El agua viene de la red de agua p\u00fablica y nosotros la purificamos<\/b><span style=\"font-weight: 400;\">. Este proceso es el mismo para los 3 puntos en los que se encuentra IGUA: El Museo de Arte Contempor\u00e1neo (MAC), la estaci\u00f3n central del Metropolitano y la bodega \u201cDany\u201d ubicada en Av. Almirante Miguel Grau cruce con Av. Nicol\u00e1s de Pi\u00e9rola en Barranco. Adem\u00e1s, todo funciona a tiempo real, nosotros monitoreamos cu\u00e1nta agua se va purificando.<\/span><\/p>\n<p><b>\u00bfQui\u00e9nes conforman el equipo de IGUA?<br \/>\n<\/b><span style=\"font-weight: 400;\">Somos un equipo interdisciplinario que involucra a estudiantes y profesionales. Por ejemplo, soy ingeniero mec\u00e1nico pero tambi\u00e9n hay personas de otras carreras. Lo genial de esto es que hemos creado un movimiento que va m\u00e1s all\u00e1 de un trabajo convencional.<\/span><\/p>\n<p><b>\u00bfQu\u00e9 significa para ti consumo responsable?<br \/>\n<\/b><span style=\"font-weight: 400;\">Hacerse cargo de uno mismo y empezar a pensar en los efectos de tu consumo en esta tierra. Todo cambio depende de uno mismo.<\/span><\/p>\n<p><b>\u00bfCu\u00e1les son los planes para IGUA?<br \/>\n<\/b><span style=\"font-weight: 400;\">Estamos trabajando para que esto sea replicable, es decir, que muchas personas puedan aplicarlo en diferentes puntos de la ciudad. <\/span><b>Nosotros empoderamos a que cualquier fuente de agua se convierta en una fuente de abastecimiento de agua. En este verano, por ejemplo, queremos llegar a tener 10 puntos y compartir 100 000 litros de agua. <\/b><span style=\"font-weight: 400;\">Otro plan para la siguiente campa\u00f1a consiste en poner <\/span><b>la dispensadora a donaci\u00f3n bajo el concepto \u201cpay as you feel\u201d<\/b><span style=\"font-weight: 400;\">. Las personas pondr\u00e1n la cantidad de dinero que sientan que merece el agua que van a consumir.<\/span><\/p>\n<p><b>\u00bfCu\u00e1l ser\u00eda el precio al llegar al mercado?<br \/>\n<\/b><span style=\"font-weight: 400;\">Los 0.50 c\u00e9ntimos establecidos fue una prueba, a mi me gustar\u00eda que cueste menos pero a\u00fan no lo sabemos. Lo importante es que la calidad de agua sea buena y en eso estamos trabajando.<\/span><\/p>\n<p><b>\u00bfQu\u00e9 recomendaciones dar\u00edas a estudiantes que quisieran emprender una iniciativa como esta?<br \/>\n<\/b><b>La teor\u00eda te dice que no lo hagas, pero el punto es atreverse.<\/b><span style=\"font-weight: 400;\"> Es importante elaborar \u00a0un plan de trabajo y validar cada ajuste que se realice. Esto asegura el \u00e9xito de cada proyecto.<\/span><\/p>\n<p><em><strong>Si quieres enterarte de las actividades que realizar\u00e1 IGUA este verano, visita sus redes sociales:<\/strong><\/em><\/p>\n<p>Facebook: <a href=\"https:\/\/www.facebook.com\/tomaigua\/\">https:\/\/www.facebook.com\/tomaigua\/<\/a><\/p>\n<p>Instagram:\u00a0<a href=\"https:\/\/www.instagram.com\/tomaigua\/?hl=es-la\">https:\/\/www.instagram.com\/tomaigua\/?hl=es-la<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>IGUA es una empresa social que tiene como finalidad brindar puntos de hidrataci\u00f3n en diversos lugares de la ciudad y garantizar el consumo de agua purificada y sostenible en el Per\u00fa. Clima de Cambios convers\u00f3 con Jos\u00e9 Corso, fundador de IGUA sobre la creaci\u00f3n de este proyecto. \u00bfCu\u00e1l fue la motivaci\u00f3n para crear IGUA? Hacer [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12401","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IGUA: Este verano, queremos compartir 100 000 litros de agua - Clima de cambios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IGUA: Este verano, queremos compartir 100 000 litros de agua - Clima de cambios\" \/>\n<meta property=\"og:description\" content=\"IGUA es una empresa social que tiene como finalidad brindar puntos de hidrataci\u00f3n en diversos lugares de la ciudad y garantizar el consumo de agua purificada y sostenible en el Per\u00fa. Clima de Cambios convers\u00f3 con Jos\u00e9 Corso, fundador de IGUA sobre la creaci\u00f3n de este proyecto. \u00bfCu\u00e1l fue la motivaci\u00f3n para crear IGUA? Hacer [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/\" \/>\n<meta property=\"og:site_name\" content=\"Clima de cambios\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-21T16:14:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-21T16:25:13+00:00\" \/>\n<meta name=\"author\" content=\"Clima de Cambios\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Clima de Cambios\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/\"},\"author\":{\"name\":\"Clima de Cambios\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79\"},\"headline\":\"IGUA: Este verano, queremos compartir 100 000 litros de agua\",\"datePublished\":\"2018-12-21T16:14:16+00:00\",\"dateModified\":\"2018-12-21T16:25:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/\"},\"wordCount\":491,\"commentCount\":0,\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/\",\"url\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/\",\"name\":\"IGUA: Este verano, queremos compartir 100 000 litros de agua - Clima de cambios\",\"isPartOf\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#website\"},\"datePublished\":\"2018-12-21T16:14:16+00:00\",\"dateModified\":\"2018-12-21T16:25:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IGUA: Este verano, queremos compartir 100 000 litros de agua\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#website\",\"url\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/\",\"name\":\"Clima de cambios\",\"description\":\"Clima de Cambios es una iniciativa medioambiental de la Pontificia Universidad Cat\u00f3lica del Per\u00fa para concientizar y sensibilizar a la ciudadan\u00eda sobre los efectos del cambio clim\u00e1tico en el Per\u00fa y el mundo.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79\",\"name\":\"Clima de Cambios\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/32dcd1482c4b98120225300dc5872038b3777d04f55b5565a634386d6edc6169?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/32dcd1482c4b98120225300dc5872038b3777d04f55b5565a634386d6edc6169?s=96&d=mm&r=g\",\"caption\":\"Clima de Cambios\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IGUA: Este verano, queremos compartir 100 000 litros de agua - Clima de cambios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/","og_locale":"es_ES","og_type":"article","og_title":"IGUA: Este verano, queremos compartir 100 000 litros de agua - Clima de cambios","og_description":"IGUA es una empresa social que tiene como finalidad brindar puntos de hidrataci\u00f3n en diversos lugares de la ciudad y garantizar el consumo de agua purificada y sostenible en el Per\u00fa. Clima de Cambios convers\u00f3 con Jos\u00e9 Corso, fundador de IGUA sobre la creaci\u00f3n de este proyecto. \u00bfCu\u00e1l fue la motivaci\u00f3n para crear IGUA? Hacer [&hellip;]","og_url":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/","og_site_name":"Clima de cambios","article_published_time":"2018-12-21T16:14:16+00:00","article_modified_time":"2018-12-21T16:25:13+00:00","author":"Clima de Cambios","twitter_misc":{"Escrito por":"Clima de Cambios","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/#article","isPartOf":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/"},"author":{"name":"Clima de Cambios","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79"},"headline":"IGUA: Este verano, queremos compartir 100 000 litros de agua","datePublished":"2018-12-21T16:14:16+00:00","dateModified":"2018-12-21T16:25:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/"},"wordCount":491,"commentCount":0,"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/","url":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/","name":"IGUA: Este verano, queremos compartir 100 000 litros de agua - Clima de cambios","isPartOf":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#website"},"datePublished":"2018-12-21T16:14:16+00:00","dateModified":"2018-12-21T16:25:13+00:00","author":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79"},"breadcrumb":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/igua-este-verano-queremos-compartir-100-000-litros-de-agua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pucp.edu.pe\/climadecambios\/"},{"@type":"ListItem","position":2,"name":"IGUA: Este verano, queremos compartir 100 000 litros de agua"}]},{"@type":"WebSite","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#website","url":"https:\/\/www.pucp.edu.pe\/climadecambios\/","name":"Clima de cambios","description":"Clima de Cambios es una iniciativa medioambiental de la Pontificia Universidad Cat\u00f3lica del Per\u00fa para concientizar y sensibilizar a la ciudadan\u00eda sobre los efectos del cambio clim\u00e1tico en el Per\u00fa y el mundo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pucp.edu.pe\/climadecambios\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/4623de9601082d7f9cdb2af6707f7c79","name":"Clima de Cambios","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/32dcd1482c4b98120225300dc5872038b3777d04f55b5565a634386d6edc6169?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32dcd1482c4b98120225300dc5872038b3777d04f55b5565a634386d6edc6169?s=96&d=mm&r=g","caption":"Clima de Cambios"}}]}},"_links":{"self":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts\/12401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/comments?post=12401"}],"version-history":[{"count":0,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts\/12401\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/media?parent=12401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/categories?post=12401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/tags?post=12401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}