{"id":11778,"date":"2017-05-05T15:16:00","date_gmt":"2017-05-05T15:16:00","guid":{"rendered":"https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/"},"modified":"2017-05-05T15:16:00","modified_gmt":"2017-05-05T15:16:00","slug":"los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza","status":"publish","type":"post","link":"https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/","title":{"rendered":"\u201cLos consejos evidencian problemas en las cuencas como la desigualdad y la pobreza\u201d"},"content":{"rendered":"<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong><span>\u00bfCu\u00e1l es el panorama de los conflictos actuales por el agua en el Per\u00fa?<\/span><\/strong><\/p>\n<p>\u00a0<\/p>\n<p>El escenario de conflictos por el agua es bastante diverso y extenso. Actualmente, tenemos el problema del Ni\u00f1o Costero con las inundaciones que est\u00e1n sucediendo en el norte, as\u00ed como los problemas de sequ\u00eda en el sur que no aparecen como conflicto, pero s\u00ed presentan un estado muy latente. Por otro lado, est\u00e1n los grandes conflictos desencadenados por la construcci\u00f3n de trasvases, por energ\u00eda, miner\u00eda y agro exportaci\u00f3n.<\/p>\n<p>\u00a0<\/p>\n<p><strong><span>\u00bfQu\u00e9 son los Consejos de Recursos H\u00eddricos y qu\u00e9 actores intervienen?<\/span><\/strong><\/p>\n<p>\u00a0<\/p>\n<p>Han sido creados a ra\u00edz de Ley de Recursos H\u00eddricos la cual se postula hacia una gesti\u00f3n integral del agua. Para que dicha gesti\u00f3n sea efectiva, es importante la creaci\u00f3n de Consejos de Recursos H\u00eddricos para cada cuenca.<\/p>\n<p>La idea es que en cada cuenca hidrogr\u00e1fica se puedan articular los distintos tipos de actores sociales que la conforman. Por un lado, est\u00e1n las ciudades, las zonas rurales y los actores presentes de la miner\u00eda y la agro exportaci\u00f3n. En ese sentido, la idea de los Consejos de Recursos H\u00eddricos es que todos los actores puedan tener una voz en este tipo de organizaci\u00f3n.<\/p>\n<p>\u00a0<\/p>\n<p><strong><span>\u00bfCu\u00e1les son las limitaciones y los desaf\u00edos para los Consejos de Recursos H\u00eddricos?<\/span><\/strong><\/p>\n<p>\u00a0<\/p>\n<p>Los Consejos de Recursos H\u00eddricos son de car\u00e1cter consultivo y no tienen financiamiento, quiere decir que no tienen ning\u00fan nivel de decisi\u00f3n y por tanto limita la posibilidad de una acci\u00f3n real y concreta.<\/p>\n<p>\u00a0<\/p>\n<p>Por otro lado, la ley nos menciona que se deben crear los Consejos de Recursos H\u00eddricos para cada cuenca, pero en la pr\u00e1ctica nos tenemos que enfrentar a la propia din\u00e1mica social, pol\u00edtica, econ\u00f3mica de cada cuenca y que incluso presenta sus propios conflictos sociales. Dicha variedad de dimensiones y particularidades a tener en cuenta, dificulta el poder tener homog\u00e9neamente Consejos de Recursos H\u00eddricos en todo el pa\u00eds.<\/p>\n<p>\u00a0<\/p>\n<p>Es por ello, que un gran desaf\u00edo para la gesti\u00f3n integral del agua es la propia diversidad geogr\u00e1fica, cultural, social y econ\u00f3mica del pa\u00eds. Los consejos evidencian problemas en las cuencas como la desigualdad y la pobreza que es necesario superar.<\/p>\n<p>\u00a0<\/p>\n<p>Cabe se\u00f1alar que foro \u201cExperiencias Latinoamericanas sobre Organismos de Cuenca\u201d, estuvo organizado por la <a href=\"http:\/\/www.ana.gob.pe\/\" target=\"_blank\">Autoridad Nacional del Agua (ANA)<\/a> y el<a href=\"http:\/\/inte.pucp.edu.pe\/\" target=\"_blank\"> Instituto de Ciencias de la Naturaleza, Territorio y Energ\u00edas Renovables (INTE- PUCP)<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00bfCu\u00e1l es el panorama de los conflictos actuales por el agua en el Per\u00fa? \u00a0 El escenario de conflictos por el agua es bastante diverso y extenso. Actualmente, tenemos el problema del Ni\u00f1o Costero con las inundaciones que est\u00e1n sucediendo en el norte, as\u00ed como los problemas de sequ\u00eda en el sur que [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[117],"tags":[],"class_list":["post-11778","post","type-post","status-publish","format-standard","hentry","category-entrevistas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cLos consejos evidencian problemas en las cuencas como la desigualdad y la pobreza\u201d - Clima de cambios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cLos consejos evidencian problemas en las cuencas como la desigualdad y la pobreza\u201d - Clima de cambios\" \/>\n<meta property=\"og:description\" content=\"\u00a0 \u00a0 \u00bfCu\u00e1l es el panorama de los conflictos actuales por el agua en el Per\u00fa? \u00a0 El escenario de conflictos por el agua es bastante diverso y extenso. Actualmente, tenemos el problema del Ni\u00f1o Costero con las inundaciones que est\u00e1n sucediendo en el norte, as\u00ed como los problemas de sequ\u00eda en el sur que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/\" \/>\n<meta property=\"og:site_name\" content=\"Clima de cambios\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-05T15:16:00+00:00\" \/>\n<meta name=\"author\" content=\"rootclimcamb\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rootclimcamb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/\"},\"author\":{\"name\":\"rootclimcamb\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3\"},\"headline\":\"\u201cLos consejos evidencian problemas en las cuencas como la desigualdad y la pobreza\u201d\",\"datePublished\":\"2017-05-05T15:16:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/\"},\"wordCount\":443,\"commentCount\":0,\"articleSection\":[\"Entrevistas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/\",\"url\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/\",\"name\":\"\u201cLos consejos evidencian problemas en las cuencas como la desigualdad y la pobreza\u201d - Clima de cambios\",\"isPartOf\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#website\"},\"datePublished\":\"2017-05-05T15:16:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cLos consejos evidencian problemas en las cuencas como la desigualdad y la pobreza\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#website\",\"url\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/\",\"name\":\"Clima de cambios\",\"description\":\"Clima de Cambios es una iniciativa medioambiental de la Pontificia Universidad Cat\u00f3lica del Per\u00fa para concientizar y sensibilizar a la ciudadan\u00eda sobre los efectos del cambio clim\u00e1tico en el Per\u00fa y el mundo.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3\",\"name\":\"rootclimcamb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g\",\"caption\":\"rootclimcamb\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cLos consejos evidencian problemas en las cuencas como la desigualdad y la pobreza\u201d - Clima de cambios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/","og_locale":"es_ES","og_type":"article","og_title":"\u201cLos consejos evidencian problemas en las cuencas como la desigualdad y la pobreza\u201d - Clima de cambios","og_description":"\u00a0 \u00a0 \u00bfCu\u00e1l es el panorama de los conflictos actuales por el agua en el Per\u00fa? \u00a0 El escenario de conflictos por el agua es bastante diverso y extenso. Actualmente, tenemos el problema del Ni\u00f1o Costero con las inundaciones que est\u00e1n sucediendo en el norte, as\u00ed como los problemas de sequ\u00eda en el sur que [&hellip;]","og_url":"https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/","og_site_name":"Clima de cambios","article_published_time":"2017-05-05T15:16:00+00:00","author":"rootclimcamb","twitter_misc":{"Escrito por":"rootclimcamb","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/#article","isPartOf":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/"},"author":{"name":"rootclimcamb","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3"},"headline":"\u201cLos consejos evidencian problemas en las cuencas como la desigualdad y la pobreza\u201d","datePublished":"2017-05-05T15:16:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/"},"wordCount":443,"commentCount":0,"articleSection":["Entrevistas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/","url":"https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/","name":"\u201cLos consejos evidencian problemas en las cuencas como la desigualdad y la pobreza\u201d - Clima de cambios","isPartOf":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#website"},"datePublished":"2017-05-05T15:16:00+00:00","author":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3"},"breadcrumb":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/entrevistas\/los-consejos-evidencian-problemas-en-las-cuencas-como-la-desigualdad-y-la-pobreza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pucp.edu.pe\/climadecambios\/"},{"@type":"ListItem","position":2,"name":"\u201cLos consejos evidencian problemas en las cuencas como la desigualdad y la pobreza\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#website","url":"https:\/\/www.pucp.edu.pe\/climadecambios\/","name":"Clima de cambios","description":"Clima de Cambios es una iniciativa medioambiental de la Pontificia Universidad Cat\u00f3lica del Per\u00fa para concientizar y sensibilizar a la ciudadan\u00eda sobre los efectos del cambio clim\u00e1tico en el Per\u00fa y el mundo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pucp.edu.pe\/climadecambios\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3","name":"rootclimcamb","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g","caption":"rootclimcamb"}}]}},"_links":{"self":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts\/11778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/comments?post=11778"}],"version-history":[{"count":0,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts\/11778\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/media?parent=11778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/categories?post=11778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/tags?post=11778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}