{"id":11603,"date":"2016-08-22T16:26:00","date_gmt":"2016-08-22T16:26:00","guid":{"rendered":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/"},"modified":"2016-08-22T16:26:00","modified_gmt":"2016-08-22T16:26:00","slug":"cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional","status":"publish","type":"post","link":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/","title":{"rendered":"Cuatro \u00e1reas naturales protegidas del Per\u00fa postulan a la Lista Verde de Conservaci\u00f3n Internacional"},"content":{"rendered":"<p>\u00a0<\/p>\n<p>El <a href=\"http:\/\/www.sernanp.gob.pe\/\" target=\"_blank\">Servicio Nacional de \u00c1reas Naturales Protegidas por el Estado (Sernanp)<\/a> busca incluir cuatro \u00e1reas naturales protegidas (ANP) en la Lista Verde del Programa Global de \u00c1reas Protegidas de la <a href=\"https:\/\/www.iucn.org\/es\/\" target=\"_blank\">Uni\u00f3n Internacional para la Conservaci\u00f3n de la Naturaleza (UICN)<\/a>, debido a sus altos est\u00e1ndares en manejo y gesti\u00f3n ambiental.<\/p>\n<p>\u00a0<\/p>\n<p>La <a href=\"http:\/\/www.iucnworldconservationcongress.org\/es\/news\/20160419\/la-lista-verde-de-la-uicn-mejorando-los-estandares-de-conservacion\" target=\"_blank\">Lista Verde de \u00c1reas Protegidas y de Conservaci\u00f3n de la UICN<\/a> es un <strong>reconocimiento que se otorga a la eficiencia de la gesti\u00f3n de un \u00e1rea natural protegida<\/strong>. A trav\u00e9s de criterios estrictos y globales, se eval\u00faa, fomenta y premia los resultados exitosos que existen en la gobernanza, planificaci\u00f3n y manejo efectivo de la conservaci\u00f3n en dichos espacios.<\/p>\n<p>\u00a0<\/p>\n<p>La Directora de Gesti\u00f3n de las \u00c1reas Naturales Protegidas del Sernanp, Cecilia Cabello, indic\u00f3 que el Per\u00fa ser\u00e1 el segundo pa\u00eds en Latinoam\u00e9rica que postular\u00e1 a esta Lista Verde, que mostrar\u00e1 el buen estado de conservaci\u00f3n y el modelo de desarrollo sostenible que promueven <strong>la Reserva Comunal Amarakaeri (Madre de Dios), el Santuario Nacional Calipuy (La Libertad), la Reserva Nacional Mats\u00e9s (Loreto) y el Parque Nacional Cordillera Azul (San Mart\u00edn, Loreto, Ucayali y Hu\u00e1nuco)<\/strong>.<\/p>\n<p>\u00a0<\/p>\n<p>Cabello tambi\u00e9n consider\u00f3 que esta es una oportunidad para mostrar el trabajo conjunto, que se viene haciendo a trav\u00e9s de un modelo de gesti\u00f3n participativa, entre el Estado peruano y actores y socios estrat\u00e9gicos. \u201cNuestros mejores aliados en las \u00e1reas naturales protegidas son los Comit\u00e9s de Gesti\u00f3n, Ejecutores de Contrato de Administraci\u00f3n (ECAs), ONG, patronatos, sector privado y poblaci\u00f3n local, conjuntamente con ellos se busca construir un desarrollo a nivel regional que les brinde mayores beneficios\u201d, se\u00f1al\u00f3.<\/p>\n<p>\u00a0<\/p>\n<p>Por otro lado, la Oficial del Proyecto de Lista Verde de la UICN, Daniela Rubio, inform\u00f3 que hasta la fecha <strong>son ocho pa\u00edses que integran esta lista, entre ellos China, Colombia, Australia, Kenia, Corea del Sur, Italia, Francia y Espa\u00f1a<\/strong>. En esta nueva fase de desarrollo, las candidaturas de nueve pa\u00edses ser\u00e1n evaluadas por expertos internacionales. Estos son Per\u00fa, M\u00e9xico, Jap\u00f3n, Malasia, Vietnam, Emiratos \u00c1rabes Unidos, Sud\u00e1frica y la regi\u00f3n de Micronesia.<\/p>\n<p>\u00a0<\/p>\n<p>Asimismo, se inici\u00f3 en Lima el taller para orientar a los administradores de las ANP que tienen inter\u00e9s en postular a esta iniciativa, dando a conocer la metodolog\u00eda que debe cumplirse y los pasos a seguir para su implementaci\u00f3n.<\/p>\n<p>\u00a0<\/p>\n<p>Durante el evento participaron representantes de la UICN, especialistas de Parques Nacionales Naturales de Colombia, la WWF (World Wildlife Fund) y los cuatro jefes de las ANP que postular\u00e1n a dicho reconocimiento acompa\u00f1ados por sus ejecutores de Contrato de Administraci\u00f3n (CIMA-Cordillera Azul, ECA Amarakaeri), as\u00ed como sus socios estrat\u00e9gicos (Patronato de la Reserva Paisaj\u00edstica Nor Yauyos Cochas, ProNaturaleza y Oceana Per\u00fa). Tambi\u00e9n estuvieron presentes la jefa de la Oficina de Asesor\u00eda Jur\u00eddica del Sernanp\u00a0 y los especialistas de la Direcci\u00f3n de Desarrollo Estrat\u00e9gico y\u00a0 la Direcci\u00f3n de Gesti\u00f3n de las \u00c1reas Naturales Protegidas.<\/p>\n<p>\u00a0<\/p>\n<p><em>Fuente: Sernanp<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 El Servicio Nacional de \u00c1reas Naturales Protegidas por el Estado (Sernanp) busca incluir cuatro \u00e1reas naturales protegidas (ANP) en la Lista Verde del Programa Global de \u00c1reas Protegidas de la Uni\u00f3n Internacional para la Conservaci\u00f3n de la Naturaleza (UICN), debido a sus altos est\u00e1ndares en manejo y gesti\u00f3n ambiental. \u00a0 La Lista Verde de [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11603","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cuatro \u00e1reas naturales protegidas del Per\u00fa postulan a la Lista Verde de Conservaci\u00f3n Internacional - Clima de cambios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuatro \u00e1reas naturales protegidas del Per\u00fa postulan a la Lista Verde de Conservaci\u00f3n Internacional - Clima de cambios\" \/>\n<meta property=\"og:description\" content=\"\u00a0 El Servicio Nacional de \u00c1reas Naturales Protegidas por el Estado (Sernanp) busca incluir cuatro \u00e1reas naturales protegidas (ANP) en la Lista Verde del Programa Global de \u00c1reas Protegidas de la Uni\u00f3n Internacional para la Conservaci\u00f3n de la Naturaleza (UICN), debido a sus altos est\u00e1ndares en manejo y gesti\u00f3n ambiental. \u00a0 La Lista Verde de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/\" \/>\n<meta property=\"og:site_name\" content=\"Clima de cambios\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-22T16:26:00+00:00\" \/>\n<meta name=\"author\" content=\"rootclimcamb\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rootclimcamb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/\"},\"author\":{\"name\":\"rootclimcamb\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3\"},\"headline\":\"Cuatro \u00e1reas naturales protegidas del Per\u00fa postulan a la Lista Verde de Conservaci\u00f3n Internacional\",\"datePublished\":\"2016-08-22T16:26:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/\"},\"wordCount\":529,\"commentCount\":0,\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/\",\"url\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/\",\"name\":\"Cuatro \u00e1reas naturales protegidas del Per\u00fa postulan a la Lista Verde de Conservaci\u00f3n Internacional - Clima de cambios\",\"isPartOf\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#website\"},\"datePublished\":\"2016-08-22T16:26:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuatro \u00e1reas naturales protegidas del Per\u00fa postulan a la Lista Verde de Conservaci\u00f3n Internacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#website\",\"url\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/\",\"name\":\"Clima de cambios\",\"description\":\"Clima de Cambios es una iniciativa medioambiental de la Pontificia Universidad Cat\u00f3lica del Per\u00fa para concientizar y sensibilizar a la ciudadan\u00eda sobre los efectos del cambio clim\u00e1tico en el Per\u00fa y el mundo.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3\",\"name\":\"rootclimcamb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g\",\"caption\":\"rootclimcamb\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuatro \u00e1reas naturales protegidas del Per\u00fa postulan a la Lista Verde de Conservaci\u00f3n Internacional - Clima de cambios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/","og_locale":"es_ES","og_type":"article","og_title":"Cuatro \u00e1reas naturales protegidas del Per\u00fa postulan a la Lista Verde de Conservaci\u00f3n Internacional - Clima de cambios","og_description":"\u00a0 El Servicio Nacional de \u00c1reas Naturales Protegidas por el Estado (Sernanp) busca incluir cuatro \u00e1reas naturales protegidas (ANP) en la Lista Verde del Programa Global de \u00c1reas Protegidas de la Uni\u00f3n Internacional para la Conservaci\u00f3n de la Naturaleza (UICN), debido a sus altos est\u00e1ndares en manejo y gesti\u00f3n ambiental. \u00a0 La Lista Verde de [&hellip;]","og_url":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/","og_site_name":"Clima de cambios","article_published_time":"2016-08-22T16:26:00+00:00","author":"rootclimcamb","twitter_misc":{"Escrito por":"rootclimcamb","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/#article","isPartOf":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/"},"author":{"name":"rootclimcamb","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3"},"headline":"Cuatro \u00e1reas naturales protegidas del Per\u00fa postulan a la Lista Verde de Conservaci\u00f3n Internacional","datePublished":"2016-08-22T16:26:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/"},"wordCount":529,"commentCount":0,"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/","url":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/","name":"Cuatro \u00e1reas naturales protegidas del Per\u00fa postulan a la Lista Verde de Conservaci\u00f3n Internacional - Clima de cambios","isPartOf":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#website"},"datePublished":"2016-08-22T16:26:00+00:00","author":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3"},"breadcrumb":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/cuatro-areas-naturales-protegidas-del-peru-postulan-a-la-lista-verde-de-conservacion-internacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pucp.edu.pe\/climadecambios\/"},{"@type":"ListItem","position":2,"name":"Cuatro \u00e1reas naturales protegidas del Per\u00fa postulan a la Lista Verde de Conservaci\u00f3n Internacional"}]},{"@type":"WebSite","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#website","url":"https:\/\/www.pucp.edu.pe\/climadecambios\/","name":"Clima de cambios","description":"Clima de Cambios es una iniciativa medioambiental de la Pontificia Universidad Cat\u00f3lica del Per\u00fa para concientizar y sensibilizar a la ciudadan\u00eda sobre los efectos del cambio clim\u00e1tico en el Per\u00fa y el mundo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pucp.edu.pe\/climadecambios\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3","name":"rootclimcamb","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g","caption":"rootclimcamb"}}]}},"_links":{"self":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts\/11603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/comments?post=11603"}],"version-history":[{"count":0,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts\/11603\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/media?parent=11603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/categories?post=11603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/tags?post=11603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}