{"id":10672,"date":"2010-01-26T17:34:00","date_gmt":"2010-01-26T17:34:00","guid":{"rendered":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/"},"modified":"2010-01-26T17:34:00","modified_gmt":"2010-01-26T17:34:00","slug":"siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica","status":"publish","type":"post","link":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/","title":{"rendered":"Siembran 6 mil \u00e1rboles en la V\u00eda Expresa del Paseo de la Rep\u00fablica"},"content":{"rendered":"<p>El pasado lunes 25 de enero, la Municipalidad de Lima culmin\u00f3 las labores de plantaci\u00f3n de <span>seis mil \u00e1rboles<\/span> de las especies tecoma y huaranguay en la V\u00eda Expresa del Paseo de la Rep\u00fablica, en el tramo comprendido entre la Plaza Grau y la bajada al Circuito de Playas. <\/p>\n<p>El objetivo de efectuar dicha arborizaci\u00f3n fue el de compatibilizar el desarrollo de la infraestructura vial que requiere nuestra capital con el <span>cuidado del medio ambiente<\/span>, de forma que se pueda tener de la forma m\u00e1s arm\u00f3nica posible una combinaci\u00f3n de cemento y ecolog\u00eda, seg\u00fan detall\u00f3 la comuna lime\u00f1a. <\/p>\n<p>Las especies tecoma y huaranguay poseen en su gran mayor\u00eda tres metros de alto y se suman al mill\u00f3n de \u00e1rboles sembrados desde el a\u00f1o 2003 por la Municipalidad de Lima en diversas partes de la capital, lo cual permite <span>purificar el aire y atenuar los vientos<\/span>.<\/p>\n<p>Gracias a lo ocurrido, Lima tendr\u00e1 un nuevo <span>cord\u00f3n ecol\u00f3gico<\/span> que contribuir\u00e1 al cuidado del medio ambiente, asegur\u00f3 el asesor de la comuna metropolitana, Armando Molina.<\/p>\n<p>Fuente e imagen: <a href=\"La Rep\u00fablica\">Andina<\/a><\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado lunes 25 de enero, la Municipalidad de Lima culmin\u00f3 las labores de plantaci\u00f3n de seis mil \u00e1rboles de las especies tecoma y huaranguay en la V\u00eda Expresa del Paseo de la Rep\u00fablica, en el tramo comprendido entre la Plaza Grau y la bajada al Circuito de Playas. El objetivo de efectuar dicha arborizaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10672","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Siembran 6 mil \u00e1rboles en la V\u00eda Expresa del Paseo de la Rep\u00fablica - Clima de cambios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Siembran 6 mil \u00e1rboles en la V\u00eda Expresa del Paseo de la Rep\u00fablica - Clima de cambios\" \/>\n<meta property=\"og:description\" content=\"El pasado lunes 25 de enero, la Municipalidad de Lima culmin\u00f3 las labores de plantaci\u00f3n de seis mil \u00e1rboles de las especies tecoma y huaranguay en la V\u00eda Expresa del Paseo de la Rep\u00fablica, en el tramo comprendido entre la Plaza Grau y la bajada al Circuito de Playas. El objetivo de efectuar dicha arborizaci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/\" \/>\n<meta property=\"og:site_name\" content=\"Clima de cambios\" \/>\n<meta property=\"article:published_time\" content=\"2010-01-26T17:34:00+00:00\" \/>\n<meta name=\"author\" content=\"rootclimcamb\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rootclimcamb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/\"},\"author\":{\"name\":\"rootclimcamb\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3\"},\"headline\":\"Siembran 6 mil \u00e1rboles en la V\u00eda Expresa del Paseo de la Rep\u00fablica\",\"datePublished\":\"2010-01-26T17:34:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/\"},\"wordCount\":202,\"commentCount\":0,\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/\",\"url\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/\",\"name\":\"Siembran 6 mil \u00e1rboles en la V\u00eda Expresa del Paseo de la Rep\u00fablica - Clima de cambios\",\"isPartOf\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#website\"},\"datePublished\":\"2010-01-26T17:34:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Siembran 6 mil \u00e1rboles en la V\u00eda Expresa del Paseo de la Rep\u00fablica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#website\",\"url\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/\",\"name\":\"Clima de cambios\",\"description\":\"Clima de Cambios es una iniciativa medioambiental de la Pontificia Universidad Cat\u00f3lica del Per\u00fa para concientizar y sensibilizar a la ciudadan\u00eda sobre los efectos del cambio clim\u00e1tico en el Per\u00fa y el mundo.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3\",\"name\":\"rootclimcamb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g\",\"caption\":\"rootclimcamb\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Siembran 6 mil \u00e1rboles en la V\u00eda Expresa del Paseo de la Rep\u00fablica - Clima de cambios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/","og_locale":"es_ES","og_type":"article","og_title":"Siembran 6 mil \u00e1rboles en la V\u00eda Expresa del Paseo de la Rep\u00fablica - Clima de cambios","og_description":"El pasado lunes 25 de enero, la Municipalidad de Lima culmin\u00f3 las labores de plantaci\u00f3n de seis mil \u00e1rboles de las especies tecoma y huaranguay en la V\u00eda Expresa del Paseo de la Rep\u00fablica, en el tramo comprendido entre la Plaza Grau y la bajada al Circuito de Playas. El objetivo de efectuar dicha arborizaci\u00f3n [&hellip;]","og_url":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/","og_site_name":"Clima de cambios","article_published_time":"2010-01-26T17:34:00+00:00","author":"rootclimcamb","twitter_misc":{"Escrito por":"rootclimcamb","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/#article","isPartOf":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/"},"author":{"name":"rootclimcamb","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3"},"headline":"Siembran 6 mil \u00e1rboles en la V\u00eda Expresa del Paseo de la Rep\u00fablica","datePublished":"2010-01-26T17:34:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/"},"wordCount":202,"commentCount":0,"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/","url":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/","name":"Siembran 6 mil \u00e1rboles en la V\u00eda Expresa del Paseo de la Rep\u00fablica - Clima de cambios","isPartOf":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#website"},"datePublished":"2010-01-26T17:34:00+00:00","author":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3"},"breadcrumb":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/siembran-6-mil-arboles-en-la-via-expresa-del-paseo-de-la-republica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pucp.edu.pe\/climadecambios\/"},{"@type":"ListItem","position":2,"name":"Siembran 6 mil \u00e1rboles en la V\u00eda Expresa del Paseo de la Rep\u00fablica"}]},{"@type":"WebSite","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#website","url":"https:\/\/www.pucp.edu.pe\/climadecambios\/","name":"Clima de cambios","description":"Clima de Cambios es una iniciativa medioambiental de la Pontificia Universidad Cat\u00f3lica del Per\u00fa para concientizar y sensibilizar a la ciudadan\u00eda sobre los efectos del cambio clim\u00e1tico en el Per\u00fa y el mundo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pucp.edu.pe\/climadecambios\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3","name":"rootclimcamb","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g","caption":"rootclimcamb"}}]}},"_links":{"self":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts\/10672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/comments?post=10672"}],"version-history":[{"count":0,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts\/10672\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/media?parent=10672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/categories?post=10672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/tags?post=10672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}