{"id":10420,"date":"2009-01-20T10:39:00","date_gmt":"2009-01-20T10:39:00","guid":{"rendered":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\/"},"modified":"2009-01-20T10:39:00","modified_gmt":"2009-01-20T10:39:00","slug":"utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama","status":"publish","type":"post","link":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\/","title":{"rendered":"\u00abUtilizaremos la fuerza del sol y el viento para mover nuestras f\u00e1bricas\u00bb, afirma Obama"},"content":{"rendered":"<p>El arribo al poder de Barack Obama como presidente de los Estados Unidos implica tambi\u00e9n cambios en la pol\u00edtica ambiental. Como se recuerda, el presidente George W. Bush rechaz\u00f3 el Protocolo de Kyoto en el 2001, alegando que ser\u00eda desastroso para la econom\u00eda de los Estados Unidos.&nbsp;&nbsp;<\/p>\n<p>El martes pasado, Hillary Clinton, designada secretaria de Estado por el presidente electo, anunci\u00f3 compromiso de Barack Obama en la lucha contra el cambio clim\u00e1tico.&nbsp;Obama, quien promover\u00e1 las energ\u00edas limpias,&nbsp;asume la presidencia de los EE.UU. hoy.<\/p>\n<p>Obama, por su parte, nombr\u00f3 un equipo de choque contra el cambio clim\u00e1tico y a favor de las energ\u00edas limpias. Entre sus miembros figura Steven Chu, premio Nobel de f\u00edsica y especialista del tema, para el cargo de ministro de Energ\u00eda. <\/p>\n<p>Fuente: PNUMA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El arribo al poder de Barack Obama como presidente de los Estados Unidos implica tambi\u00e9n cambios en la pol\u00edtica ambiental. Como se recuerda, el presidente George W. Bush rechaz\u00f3 el Protocolo de Kyoto en el 2001, alegando que ser\u00eda desastroso para la econom\u00eda de los Estados Unidos.&nbsp;&nbsp; El martes pasado, Hillary Clinton, designada secretaria de [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10420","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Utilizaremos la fuerza del sol y el viento para mover nuestras f\u00e1bricas&quot;, afirma Obama - Clima de cambios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Utilizaremos la fuerza del sol y el viento para mover nuestras f\u00e1bricas&quot;, afirma Obama - Clima de cambios\" \/>\n<meta property=\"og:description\" content=\"El arribo al poder de Barack Obama como presidente de los Estados Unidos implica tambi\u00e9n cambios en la pol\u00edtica ambiental. Como se recuerda, el presidente George W. Bush rechaz\u00f3 el Protocolo de Kyoto en el 2001, alegando que ser\u00eda desastroso para la econom\u00eda de los Estados Unidos.&nbsp;&nbsp; El martes pasado, Hillary Clinton, designada secretaria de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\/\" \/>\n<meta property=\"og:site_name\" content=\"Clima de cambios\" \/>\n<meta property=\"article:published_time\" content=\"2009-01-20T10:39:00+00:00\" \/>\n<meta name=\"author\" content=\"rootclimcamb\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rootclimcamb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\\\/\"},\"author\":{\"name\":\"rootclimcamb\",\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/#\\\/schema\\\/person\\\/e3246e899a153f8a2b27227abf9491b3\"},\"headline\":\"\u00abUtilizaremos la fuerza del sol y el viento para mover nuestras f\u00e1bricas\u00bb, afirma Obama\",\"datePublished\":\"2009-01-20T10:39:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\\\/\"},\"wordCount\":157,\"commentCount\":0,\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\\\/\",\"url\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\\\/\",\"name\":\"\\\"Utilizaremos la fuerza del sol y el viento para mover nuestras f\u00e1bricas\\\", afirma Obama - Clima de cambios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/#website\"},\"datePublished\":\"2009-01-20T10:39:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/#\\\/schema\\\/person\\\/e3246e899a153f8a2b27227abf9491b3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abUtilizaremos la fuerza del sol y el viento para mover nuestras f\u00e1bricas\u00bb, afirma Obama\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/#website\",\"url\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/\",\"name\":\"Clima de cambios\",\"description\":\"Clima de Cambios es una iniciativa medioambiental de la Pontificia Universidad Cat\u00f3lica del Per\u00fa para concientizar y sensibilizar a la ciudadan\u00eda sobre los efectos del cambio clim\u00e1tico en el Per\u00fa y el mundo.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/#\\\/schema\\\/person\\\/e3246e899a153f8a2b27227abf9491b3\",\"name\":\"rootclimcamb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g\",\"caption\":\"rootclimcamb\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Utilizaremos la fuerza del sol y el viento para mover nuestras f\u00e1bricas\", afirma Obama - Clima de cambios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\/","og_locale":"es_ES","og_type":"article","og_title":"\"Utilizaremos la fuerza del sol y el viento para mover nuestras f\u00e1bricas\", afirma Obama - Clima de cambios","og_description":"El arribo al poder de Barack Obama como presidente de los Estados Unidos implica tambi\u00e9n cambios en la pol\u00edtica ambiental. Como se recuerda, el presidente George W. Bush rechaz\u00f3 el Protocolo de Kyoto en el 2001, alegando que ser\u00eda desastroso para la econom\u00eda de los Estados Unidos.&nbsp;&nbsp; El martes pasado, Hillary Clinton, designada secretaria de [&hellip;]","og_url":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\/","og_site_name":"Clima de cambios","article_published_time":"2009-01-20T10:39:00+00:00","author":"rootclimcamb","twitter_misc":{"Escrito por":"rootclimcamb","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\/#article","isPartOf":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\/"},"author":{"name":"rootclimcamb","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3"},"headline":"\u00abUtilizaremos la fuerza del sol y el viento para mover nuestras f\u00e1bricas\u00bb, afirma Obama","datePublished":"2009-01-20T10:39:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\/"},"wordCount":157,"commentCount":0,"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\/","url":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\/","name":"\"Utilizaremos la fuerza del sol y el viento para mover nuestras f\u00e1bricas\", afirma Obama - Clima de cambios","isPartOf":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#website"},"datePublished":"2009-01-20T10:39:00+00:00","author":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3"},"breadcrumb":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/utilizaremos-la-fuerza-del-sol-y-el-viento-para-mover-nuestras-fabricas-afirma-obama\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pucp.edu.pe\/climadecambios\/"},{"@type":"ListItem","position":2,"name":"\u00abUtilizaremos la fuerza del sol y el viento para mover nuestras f\u00e1bricas\u00bb, afirma Obama"}]},{"@type":"WebSite","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#website","url":"https:\/\/www.pucp.edu.pe\/climadecambios\/","name":"Clima de cambios","description":"Clima de Cambios es una iniciativa medioambiental de la Pontificia Universidad Cat\u00f3lica del Per\u00fa para concientizar y sensibilizar a la ciudadan\u00eda sobre los efectos del cambio clim\u00e1tico en el Per\u00fa y el mundo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pucp.edu.pe\/climadecambios\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3","name":"rootclimcamb","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g","caption":"rootclimcamb"}}]}},"_links":{"self":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts\/10420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/comments?post=10420"}],"version-history":[{"count":0,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts\/10420\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/media?parent=10420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/categories?post=10420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/tags?post=10420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}