{"id":10403,"date":"2008-12-08T15:38:00","date_gmt":"2008-12-08T15:38:00","guid":{"rendered":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\/"},"modified":"2008-12-08T15:38:00","modified_gmt":"2008-12-08T15:38:00","slug":"ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores","status":"publish","type":"post","link":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\/","title":{"rendered":"Ministerio del Ambiente elabora estrategia contra el cambio clim\u00e1tico junto a otros sectores"},"content":{"rendered":"<p>El Ministerio del Ambiente trabaja la Segunda Comunicaci\u00f3n Nacional de Cambio Clim\u00e1tico, en la que emplea futuros escenarios de cambio clim\u00e1tico en cuencas priorizadas gracias a los reportes climatol\u00f3gicos del Servicio Nacional de Meteorolog\u00eda e Hidrolog\u00eda (SENAMHI). De esta forma se establecer\u00e1n las acciones de mitigaci\u00f3n ante la alta vulnerabilidad del Per&uacute;. Los ministerios involucrados eval&uacute;an en conjunto los efectos. <\/p>\n<p>Estos trabajos se enmarcan en el compromiso asumido por el Per&uacute; al ser parte de la Convenci\u00f3n Marco de las Naciones Unidas sobre Cambio Clim\u00e1tico. Nuestro pa\u00eds representa casi el 0,4% de las emisiones totales mundiales de CO2. En el 2000, esas emisiones fueron ocasionadas principalmente por la deforestaci\u00f3n 47% del total nacional, seguido por las actividades para la producci\u00f3n de energ\u00eda, con 21%. &nbsp;`<\/p>\n<p>Fuente: <a href=\"http:\/\/www.inforegion.com.pe\/region\/noticia_detalle.php?v_idnoticia=19154&amp;v_idlocacion=1&amp;v_idcategoria=28\" target=\"_blank\">Inforegi\u00f3n<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio del Ambiente trabaja la Segunda Comunicaci\u00f3n Nacional de Cambio Clim\u00e1tico, en la que emplea futuros escenarios de cambio clim\u00e1tico en cuencas priorizadas gracias a los reportes climatol\u00f3gicos del Servicio Nacional de Meteorolog\u00eda e Hidrolog\u00eda (SENAMHI). De esta forma se establecer\u00e1n las acciones de mitigaci\u00f3n ante la alta vulnerabilidad del Per&uacute;. Los ministerios involucrados [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10403","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ministerio del Ambiente elabora estrategia contra el cambio clim\u00e1tico junto a otros sectores - Clima de cambios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ministerio del Ambiente elabora estrategia contra el cambio clim\u00e1tico junto a otros sectores - Clima de cambios\" \/>\n<meta property=\"og:description\" content=\"El Ministerio del Ambiente trabaja la Segunda Comunicaci\u00f3n Nacional de Cambio Clim\u00e1tico, en la que emplea futuros escenarios de cambio clim\u00e1tico en cuencas priorizadas gracias a los reportes climatol\u00f3gicos del Servicio Nacional de Meteorolog\u00eda e Hidrolog\u00eda (SENAMHI). De esta forma se establecer\u00e1n las acciones de mitigaci\u00f3n ante la alta vulnerabilidad del Per&uacute;. Los ministerios involucrados [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\/\" \/>\n<meta property=\"og:site_name\" content=\"Clima de cambios\" \/>\n<meta property=\"article:published_time\" content=\"2008-12-08T15:38:00+00:00\" \/>\n<meta name=\"author\" content=\"rootclimcamb\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rootclimcamb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\\\/\"},\"author\":{\"name\":\"rootclimcamb\",\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/#\\\/schema\\\/person\\\/e3246e899a153f8a2b27227abf9491b3\"},\"headline\":\"Ministerio del Ambiente elabora estrategia contra el cambio clim\u00e1tico junto a otros sectores\",\"datePublished\":\"2008-12-08T15:38:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\\\/\"},\"wordCount\":156,\"commentCount\":0,\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\\\/\",\"url\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\\\/\",\"name\":\"Ministerio del Ambiente elabora estrategia contra el cambio clim\u00e1tico junto a otros sectores - Clima de cambios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/#website\"},\"datePublished\":\"2008-12-08T15:38:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/#\\\/schema\\\/person\\\/e3246e899a153f8a2b27227abf9491b3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ministerio del Ambiente elabora estrategia contra el cambio clim\u00e1tico junto a otros sectores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/#website\",\"url\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/\",\"name\":\"Clima de cambios\",\"description\":\"Clima de Cambios es una iniciativa medioambiental de la Pontificia Universidad Cat\u00f3lica del Per\u00fa para concientizar y sensibilizar a la ciudadan\u00eda sobre los efectos del cambio clim\u00e1tico en el Per\u00fa y el mundo.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/#\\\/schema\\\/person\\\/e3246e899a153f8a2b27227abf9491b3\",\"name\":\"rootclimcamb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g\",\"caption\":\"rootclimcamb\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ministerio del Ambiente elabora estrategia contra el cambio clim\u00e1tico junto a otros sectores - Clima de cambios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\/","og_locale":"es_ES","og_type":"article","og_title":"Ministerio del Ambiente elabora estrategia contra el cambio clim\u00e1tico junto a otros sectores - Clima de cambios","og_description":"El Ministerio del Ambiente trabaja la Segunda Comunicaci\u00f3n Nacional de Cambio Clim\u00e1tico, en la que emplea futuros escenarios de cambio clim\u00e1tico en cuencas priorizadas gracias a los reportes climatol\u00f3gicos del Servicio Nacional de Meteorolog\u00eda e Hidrolog\u00eda (SENAMHI). De esta forma se establecer\u00e1n las acciones de mitigaci\u00f3n ante la alta vulnerabilidad del Per&uacute;. Los ministerios involucrados [&hellip;]","og_url":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\/","og_site_name":"Clima de cambios","article_published_time":"2008-12-08T15:38:00+00:00","author":"rootclimcamb","twitter_misc":{"Escrito por":"rootclimcamb","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\/#article","isPartOf":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\/"},"author":{"name":"rootclimcamb","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3"},"headline":"Ministerio del Ambiente elabora estrategia contra el cambio clim\u00e1tico junto a otros sectores","datePublished":"2008-12-08T15:38:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\/"},"wordCount":156,"commentCount":0,"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\/","url":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\/","name":"Ministerio del Ambiente elabora estrategia contra el cambio clim\u00e1tico junto a otros sectores - Clima de cambios","isPartOf":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#website"},"datePublished":"2008-12-08T15:38:00+00:00","author":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3"},"breadcrumb":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/ministerio-del-ambiente-elabora-estrategia-contra-el-cambio-climatico-junto-a-otros-sectores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pucp.edu.pe\/climadecambios\/"},{"@type":"ListItem","position":2,"name":"Ministerio del Ambiente elabora estrategia contra el cambio clim\u00e1tico junto a otros sectores"}]},{"@type":"WebSite","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#website","url":"https:\/\/www.pucp.edu.pe\/climadecambios\/","name":"Clima de cambios","description":"Clima de Cambios es una iniciativa medioambiental de la Pontificia Universidad Cat\u00f3lica del Per\u00fa para concientizar y sensibilizar a la ciudadan\u00eda sobre los efectos del cambio clim\u00e1tico en el Per\u00fa y el mundo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pucp.edu.pe\/climadecambios\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3","name":"rootclimcamb","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g","caption":"rootclimcamb"}}]}},"_links":{"self":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts\/10403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/comments?post=10403"}],"version-history":[{"count":0,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts\/10403\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/media?parent=10403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/categories?post=10403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/tags?post=10403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}