{"id":10399,"date":"2008-12-01T11:46:00","date_gmt":"2008-12-01T11:46:00","guid":{"rendered":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\/"},"modified":"2008-12-01T11:46:00","modified_gmt":"2008-12-01T11:46:00","slug":"la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar","status":"publish","type":"post","link":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\/","title":{"rendered":"La Casa de Cart\u00f3n y H\u00e9ctor de C\u00e1rdenas ganan Concurso de Responsabilidad Social Escolar"},"content":{"rendered":"<p><span>La emoci\u00f3n se apoder\u00f3 de los alumnos de los colegios La Casa de Cart\u00f3n y H\u00e9ctor de C\u00e1rdenas cuando el pasado s\u00e1bado 29 fueron anunciados como ganadores del primer Concurso de Responsabilidad Social Escolar. El proyecto 263 hect\u00e1reas que cuidar, de La Casa de Cart\u00f3n involucr\u00f3 a todos los alumnos en el cuidado de los humedales de Villa. Los estudiantes del colegio H\u00e9ctor de C\u00e1rdenas, por su parte, se encargaron de mejorar el proyecto Las Laderas del R\u00edo Chill\u00f3n, mediante el cual trabajan con la comunidad.&nbsp;<\/span><span>Los finalistas fueron los colegios Am\u00e9rica (Reciclart), Claretiano (Expresarte) y San Antonio de Padua (Cuerpo de L\u00edderes).<\/p>\n<p><\/span><span>Este primer concurso, convocado a inicios de a\u00f1o por la Oficina Central de Admisi\u00f3n de la Universidad, estuvo dirigido a los escolares desde 3&deg; a 5&deg; de secundaria para incentivar la capacidad de analizar la realidad, identificar problemas, proponer soluciones y liderarlas. Cada colegio, representado por un equipo, formul\u00f3 sus proyectos, presupuestos, busc\u00f3 financiamiento y evalu\u00f3 el impacto de sus acciones, desde el enfoque de responsabilidad social. <\/p>\n<p><a href=\"index.php?option=com_blog&amp;task=view_content&amp;id=285\">Conoce m\u00e1s sobre sus proyectos en nuestro blog.<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La emoci\u00f3n se apoder\u00f3 de los alumnos de los colegios La Casa de Cart\u00f3n y H\u00e9ctor de C\u00e1rdenas cuando el pasado s\u00e1bado 29 fueron anunciados como ganadores del primer Concurso de Responsabilidad Social Escolar. El proyecto 263 hect\u00e1reas que cuidar, de La Casa de Cart\u00f3n involucr\u00f3 a todos los alumnos en el cuidado de los [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10399","post","type-post","status-publish","format-standard","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Casa de Cart\u00f3n y H\u00e9ctor de C\u00e1rdenas ganan Concurso de Responsabilidad Social Escolar - Clima de cambios<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Casa de Cart\u00f3n y H\u00e9ctor de C\u00e1rdenas ganan Concurso de Responsabilidad Social Escolar - Clima de cambios\" \/>\n<meta property=\"og:description\" content=\"La emoci\u00f3n se apoder\u00f3 de los alumnos de los colegios La Casa de Cart\u00f3n y H\u00e9ctor de C\u00e1rdenas cuando el pasado s\u00e1bado 29 fueron anunciados como ganadores del primer Concurso de Responsabilidad Social Escolar. El proyecto 263 hect\u00e1reas que cuidar, de La Casa de Cart\u00f3n involucr\u00f3 a todos los alumnos en el cuidado de los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\/\" \/>\n<meta property=\"og:site_name\" content=\"Clima de cambios\" \/>\n<meta property=\"article:published_time\" content=\"2008-12-01T11:46:00+00:00\" \/>\n<meta name=\"author\" content=\"rootclimcamb\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rootclimcamb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\\\/\"},\"author\":{\"name\":\"rootclimcamb\",\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/#\\\/schema\\\/person\\\/e3246e899a153f8a2b27227abf9491b3\"},\"headline\":\"La Casa de Cart\u00f3n y H\u00e9ctor de C\u00e1rdenas ganan Concurso de Responsabilidad Social Escolar\",\"datePublished\":\"2008-12-01T11:46:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\\\/\"},\"wordCount\":210,\"commentCount\":0,\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\\\/\",\"url\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\\\/\",\"name\":\"La Casa de Cart\u00f3n y H\u00e9ctor de C\u00e1rdenas ganan Concurso de Responsabilidad Social Escolar - Clima de cambios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/#website\"},\"datePublished\":\"2008-12-01T11:46:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/#\\\/schema\\\/person\\\/e3246e899a153f8a2b27227abf9491b3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/noticias\\\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Casa de Cart\u00f3n y H\u00e9ctor de C\u00e1rdenas ganan Concurso de Responsabilidad Social Escolar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/#website\",\"url\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/\",\"name\":\"Clima de cambios\",\"description\":\"Clima de Cambios es una iniciativa medioambiental de la Pontificia Universidad Cat\u00f3lica del Per\u00fa para concientizar y sensibilizar a la ciudadan\u00eda sobre los efectos del cambio clim\u00e1tico en el Per\u00fa y el mundo.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pucp.edu.pe\\\/climadecambios\\\/#\\\/schema\\\/person\\\/e3246e899a153f8a2b27227abf9491b3\",\"name\":\"rootclimcamb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g\",\"caption\":\"rootclimcamb\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Casa de Cart\u00f3n y H\u00e9ctor de C\u00e1rdenas ganan Concurso de Responsabilidad Social Escolar - Clima de cambios","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\/","og_locale":"es_ES","og_type":"article","og_title":"La Casa de Cart\u00f3n y H\u00e9ctor de C\u00e1rdenas ganan Concurso de Responsabilidad Social Escolar - Clima de cambios","og_description":"La emoci\u00f3n se apoder\u00f3 de los alumnos de los colegios La Casa de Cart\u00f3n y H\u00e9ctor de C\u00e1rdenas cuando el pasado s\u00e1bado 29 fueron anunciados como ganadores del primer Concurso de Responsabilidad Social Escolar. El proyecto 263 hect\u00e1reas que cuidar, de La Casa de Cart\u00f3n involucr\u00f3 a todos los alumnos en el cuidado de los [&hellip;]","og_url":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\/","og_site_name":"Clima de cambios","article_published_time":"2008-12-01T11:46:00+00:00","author":"rootclimcamb","twitter_misc":{"Escrito por":"rootclimcamb","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\/#article","isPartOf":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\/"},"author":{"name":"rootclimcamb","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3"},"headline":"La Casa de Cart\u00f3n y H\u00e9ctor de C\u00e1rdenas ganan Concurso de Responsabilidad Social Escolar","datePublished":"2008-12-01T11:46:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\/"},"wordCount":210,"commentCount":0,"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\/","url":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\/","name":"La Casa de Cart\u00f3n y H\u00e9ctor de C\u00e1rdenas ganan Concurso de Responsabilidad Social Escolar - Clima de cambios","isPartOf":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#website"},"datePublished":"2008-12-01T11:46:00+00:00","author":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3"},"breadcrumb":{"@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/noticias\/la-casa-de-carton-y-hector-de-cardenas-ganan-concurso-de-responsabilidad-social-escolar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pucp.edu.pe\/climadecambios\/"},{"@type":"ListItem","position":2,"name":"La Casa de Cart\u00f3n y H\u00e9ctor de C\u00e1rdenas ganan Concurso de Responsabilidad Social Escolar"}]},{"@type":"WebSite","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#website","url":"https:\/\/www.pucp.edu.pe\/climadecambios\/","name":"Clima de cambios","description":"Clima de Cambios es una iniciativa medioambiental de la Pontificia Universidad Cat\u00f3lica del Per\u00fa para concientizar y sensibilizar a la ciudadan\u00eda sobre los efectos del cambio clim\u00e1tico en el Per\u00fa y el mundo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pucp.edu.pe\/climadecambios\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.pucp.edu.pe\/climadecambios\/#\/schema\/person\/e3246e899a153f8a2b27227abf9491b3","name":"rootclimcamb","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/816639029a1fa304cdcc0f06aba5da891c3298c8ba4091a68fa355f22568bef1?s=96&d=mm&r=g","caption":"rootclimcamb"}}]}},"_links":{"self":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts\/10399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/comments?post=10399"}],"version-history":[{"count":0,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/posts\/10399\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/media?parent=10399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/categories?post=10399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pucp.edu.pe\/climadecambios\/wp-json\/wp\/v2\/tags?post=10399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}